{"id":26150,"date":"2026-04-30T12:54:05","date_gmt":"2026-04-30T16:54:05","guid":{"rendered":"https:\/\/npm.org\/?p=26150"},"modified":"2026-05-12T14:16:34","modified_gmt":"2026-05-12T18:16:34","slug":"npm-town-hall-meetings-information","status":"publish","type":"post","link":"https:\/\/npm.org\/es\/2026\/04\/30\/npm-town-hall-meetings-information\/","title":{"rendered":"Informaci\u00f3n sobre las reuniones p\u00fablicas del NPM"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26150\" class=\"elementor elementor-26150\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e6e4c6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e6e4c6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c68f1b\" data-id=\"7c68f1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80bbe0a elementor-widget elementor-widget-text-editor\" data-id=\"80bbe0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 14pt;\">Mientras consideramos un posible cambio de nombre para NPM, invitamos a todos los miembros activos a una de las dos reuniones informativas que celebraremos. Deseamos entablar un di\u00e1logo m\u00e1s profundo, en el esp\u00edritu del proceso sinodal que, como Iglesia, hemos llevado a cabo en los \u00faltimos a\u00f1os.\u00a0<\/span><\/p><p><span style=\"font-size: 14pt;\">Utilice estos enlaces para inscribirse en la reuni\u00f3n del Ayuntamiento en una de las dos fechas; le rogamos que se inscriba en una sola fecha para que el mayor n\u00famero posible de miembros pueda participar:\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6350131 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6350131\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0dbf893\" data-id=\"0dbf893\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23d2265 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"23d2265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/npm.site-ym.com\/events\/EventDetails.aspx?id=2058740\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\"> Martes 19 de mayo de 2026 a las 20:00 ET \/ 17:00 PT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3f35d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3f35d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-520d23a\" data-id=\"520d23a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2f4f79 elementor-widget elementor-widget-text-editor\" data-id=\"f2f4f79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><span style=\"font-size: 14pt;\">Ambas reuniones del Ayuntamiento ser\u00e1n grabadas (a trav\u00e9s de Zoom) para que la Junta pueda revisarlas en nuestras deliberaciones.\u00a0<\/span><\/li><li><span style=\"font-size: 14pt;\">Los inscritos tendr\u00e1n la oportunidad de hablar; se utilizar\u00e1 un l\u00edmite de 2 minutos por persona para que podamos escuchar hasta 30 miembros en una reuni\u00f3n. Su confirmaci\u00f3n de inscripci\u00f3n incluir\u00e1 instrucciones para indicar con anticipaci\u00f3n si desea ser orador.<\/span><\/li><li><span style=\"font-size: 14pt;\">Si bien no podremos escuchar a todos, haremos todo lo posible para garantizar que se tengan en cuenta los comentarios desde diferentes perspectivas.\u00a0<\/span><\/li><li><span style=\"font-size: 14pt;\">Y, como siempre, les invitamos a que nos env\u00eden un correo electr\u00f3nico con sus comentarios adicionales despu\u00e9s de la reuni\u00f3n.\u00a0<\/span><\/li><\/ul><p><span style=\"font-size: 14pt;\">Nos sentimos honrados y agradecidos por su respuesta a esta iniciativa y por su compromiso con el futuro de la Asociaci\u00f3n. Esperamos contar con su presencia en una de las dos pr\u00f3ximas reuniones informativas.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>As we contemplate a potential name change for NPM, we invite all active members to one of two Town Hall meetings. We want to engage in further dialogue, in the spirit of\u00a0the synodal process we as a Church have undergone in the past several years.\u00a0 Please use these links to register for the Town Hall [&hellip;]<\/p>\n","protected":false},"author":3640,"featured_media":26154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/posts\/26150"}],"collection":[{"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/users\/3640"}],"replies":[{"embeddable":true,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/comments?post=26150"}],"version-history":[{"count":7,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/posts\/26150\/revisions"}],"predecessor-version":[{"id":26174,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/posts\/26150\/revisions\/26174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/media\/26154"}],"wp:attachment":[{"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/media?parent=26150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/categories?post=26150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/npm.org\/es\/wp-json\/wp\/v2\/tags?post=26150"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}